{"id":322,"date":"2026-06-12T15:57:01","date_gmt":"2026-06-12T15:57:01","guid":{"rendered":"https:\/\/a2byourself.com\/?page_id=322"},"modified":"2026-06-12T17:07:52","modified_gmt":"2026-06-12T17:07:52","slug":"business","status":"publish","type":"page","link":"https:\/\/a2byourself.com\/en\/business\/","title":{"rendered":"Business"},"content":{"rendered":"<p>[et_pb_section fb_built=&#8221;1&#8243; fullwidth=&#8221;on&#8221; next_background_color=&#8221;RGBA(255,255,255,0)&#8221; _builder_version=&#8221;4.16&#8243; bottom_divider_style=&#8221;slant&#8221; bottom_divider_flip=&#8221;horizontal&#8221; animation_direction=&#8221;top&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_fullwidth_header title=&#8221;Business com Diego Rodrigues&#8221; subhead=&#8221;Estrategista pessoal | Bacharel em Psicologia | Life Coach Certificado&#8221; text_orientation=&#8221;center&#8221; background_overlay_color=&#8221;rgba(52,81,104,0.8)&#8221; _builder_version=&#8221;4.27.4&#8243; title_font=&#8221;Lato|700|||||||&#8221; title_font_size=&#8221;46px&#8221; title_line_height=&#8221;1.5em&#8221; content_font=&#8221;Lato||||||||&#8221; content_font_size=&#8221;20px&#8221; content_line_height=&#8221;1.8em&#8221; subhead_font=&#8221;Lato|700|||||||&#8221; subhead_font_size=&#8221;25px&#8221; subhead_line_height=&#8221;1.5em&#8221; background_color=&#8221;#afafaf&#8221; background_image=&#8221;https:\/\/a2byourself.com\/wp-content\/uploads\/2026\/03\/WhatsApp-Image-2026-03-08-at-18.39.36.webp&#8221; parallax=&#8221;on&#8221; custom_margin=&#8221;|||&#8221; custom_padding=&#8221;5vw||150px||false&#8221; animation_style=&#8221;slide&#8221; animation_direction=&#8221;top&#8221; animation_intensity_slide=&#8221;2%&#8221; title_font_size_tablet=&#8221;36px&#8221; title_font_size_phone=&#8221;&#8221; title_font_size_last_edited=&#8221;on|phone&#8221; global_colors_info=&#8221;{}&#8221; button_one_text_size__hover_enabled=&#8221;off&#8221; button_two_text_size__hover_enabled=&#8221;off&#8221; button_one_text_color__hover_enabled=&#8221;off&#8221; button_two_text_color__hover_enabled=&#8221;off&#8221; button_one_border_width__hover_enabled=&#8221;off&#8221; button_two_border_width__hover_enabled=&#8221;off&#8221; button_one_border_color__hover_enabled=&#8221;off&#8221; button_two_border_color__hover_enabled=&#8221;off&#8221; button_one_border_radius__hover_enabled=&#8221;off&#8221; button_two_border_radius__hover_enabled=&#8221;off&#8221; button_one_letter_spacing__hover_enabled=&#8221;off&#8221; button_two_letter_spacing__hover_enabled=&#8221;off&#8221; button_one_bg_color__hover_enabled=&#8221;off&#8221; button_two_bg_color__hover_enabled=&#8221;off&#8221;]<\/p>\n<p><span>Voc\u00ea n\u00e3o precisa se reinventar. Precisa organizar suas a\u00e7\u00f5es e disciplinar seus comportamentos.<\/span><\/p>\n<p>[\/et_pb_fullwidth_header][\/et_pb_section][et_pb_section fb_built=&#8221;1&#8243; next_background_color=&#8221;#ffffff&#8221; admin_label=&#8221;Services&#8221; _builder_version=&#8221;4.27.4&#8243; background_color=&#8221;RGBA(255,255,255,0)&#8221; custom_padding=&#8221;0|0px|0|0px|true|false&#8221; bottom_divider_style=&#8221;slant&#8221; bottom_divider_flip=&#8221;horizontal&#8221; bottom_divider_arrangement=&#8221;above_content&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_row column_structure=&#8221;1_4,1_4,1_4,1_4&#8243; use_custom_gutter=&#8221;on&#8221; gutter_width=&#8221;1&#8243; make_equal=&#8221;on&#8221; padding_top_bottom_link_1=&#8221;false&#8221; padding_top_bottom_link_2=&#8221;false&#8221; padding_top_bottom_link_3=&#8221;false&#8221; padding_top_bottom_link_4=&#8221;false&#8221; padding_left_right_link_1=&#8221;true&#8221; padding_left_right_link_2=&#8221;true&#8221; padding_left_right_link_3=&#8221;true&#8221; padding_left_right_link_4=&#8221;true&#8221; module_class=&#8221; et_pb_row_fullwidth&#8221; _builder_version=&#8221;4.16&#8243; width=&#8221;100%&#8221; width_tablet=&#8221;100%&#8221; width_phone=&#8221;100%&#8221; width_last_edited=&#8221;on|desktop&#8221; max_width=&#8221;100%&#8221; max_width_tablet=&#8221;100%&#8221; max_width_phone=&#8221;100%&#8221; max_width_last_edited=&#8221;on|desktop&#8221; custom_margin=&#8221;|||&#8221; custom_padding=&#8221;0px|0px|0|0px|false|false&#8221; make_fullwidth=&#8221;on&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;1_4&#8243; _builder_version=&#8221;4.16&#8243; background_color=&#8221;#c4cace&#8221; use_background_color_gradient=&#8221;on&#8221; background_color_gradient_stops=&#8221;#ffd088 0%|#ffb356 70%&#8221; background_color_gradient_start=&#8221;#ffd088&#8243; background_color_gradient_end=&#8221;#ffb356&#8243; background_color_gradient_end_position=&#8221;70%&#8221; custom_padding=&#8221;80px|40px|150px|40px&#8221; custom_padding_tablet=&#8221;20px||60px|&#8221; custom_padding_phone=&#8221;60px||60px||true&#8221; custom_padding_last_edited=&#8221;on|phone&#8221; global_colors_info=&#8221;{}&#8221; padding_phone=&#8221;60px||60px||true&#8221; padding_tablet=&#8221;20px||60px|&#8221; padding_last_edited=&#8221;on|phone&#8221; custom_padding__hover=&#8221;|||&#8221;][et_pb_blurb title=&#8221;Foco&#8221; use_icon=&#8221;on&#8221; font_icon=&#8221;&#xe0f5;||divi||400&#8243; icon_color=&#8221;#345168&#8243; image_icon_width=&#8221;32px&#8221; _builder_version=&#8221;4.27.4&#8243; header_level=&#8221;h3&#8243; header_font=&#8221;Lato|700|||||||&#8221; header_line_height=&#8221;1.5em&#8221; body_font=&#8221;Lato||||||||&#8221; body_font_size=&#8221;18px&#8221; body_line_height=&#8221;1.8em&#8221; text_orientation=&#8221;center&#8221; background_layout=&#8221;dark&#8221; max_width=&#8221;340px&#8221; module_alignment=&#8221;center&#8221; custom_margin=&#8221;||30px|&#8221; animation_style=&#8221;slide&#8221; animation_direction=&#8221;bottom&#8221; animation_intensity_slide=&#8221;5%&#8221; icon_font_size=&#8221;32px&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<p data-start=\"0\" data-end=\"177\" style=\"text-align: justify;\"><span>Sua mente deixa de ser um campo de distra\u00e7\u00f5es e passa a trabalhar a seu favor. Voc\u00ea reduz a dispers\u00e3o, organiza pensamentos e transforma inquieta\u00e7\u00e3o em dire\u00e7\u00e3o estrat\u00e9gica e a\u00e7\u00e3o produtiva.<\/span><\/p>\n<p data-start=\"179\" data-end=\"340\">[\/et_pb_blurb][\/et_pb_column][et_pb_column type=&#8221;1_4&#8243; _builder_version=&#8221;4.16&#8243; background_color=&#8221;#cbd0d6&#8243; use_background_color_gradient=&#8221;on&#8221; background_color_gradient_stops=&#8221;#ffd088 0%|#ffbe6b 70%&#8221; background_color_gradient_start=&#8221;#ffd088&#8243; background_color_gradient_end=&#8221;#ffbe6b&#8221; background_color_gradient_end_position=&#8221;70%&#8221; custom_padding=&#8221;70px|40px|150px|40px&#8221; custom_padding_tablet=&#8221;20px||60px|&#8221; custom_padding_phone=&#8221;60px||60px||true&#8221; custom_padding_last_edited=&#8221;on|phone&#8221; global_colors_info=&#8221;{}&#8221; padding_phone=&#8221;60px||60px||true&#8221; padding_tablet=&#8221;20px||60px|&#8221; padding_last_edited=&#8221;on|phone&#8221; custom_padding__hover=&#8221;|||&#8221;][et_pb_blurb title=&#8221;Const\u00e2ncia&#8221; use_icon=&#8221;on&#8221; font_icon=&#8221;&#xe08b;||divi||400&#8243; icon_color=&#8221;#345168&#8243; image_icon_width=&#8221;32px&#8221; _builder_version=&#8221;4.27.4&#8243; header_level=&#8221;h3&#8243; header_font=&#8221;Lato|700|||||||&#8221; header_line_height=&#8221;1.5em&#8221; body_font=&#8221;Lato||||||||&#8221; body_font_size=&#8221;18px&#8221; body_line_height=&#8221;1.8em&#8221; text_orientation=&#8221;center&#8221; background_layout=&#8221;dark&#8221; max_width=&#8221;340px&#8221; module_alignment=&#8221;center&#8221; custom_margin=&#8221;||30px|&#8221; animation_style=&#8221;slide&#8221; animation_direction=&#8221;bottom&#8221; animation_delay=&#8221;100ms&#8221; animation_intensity_slide=&#8221;5%&#8221; icon_font_size=&#8221;32px&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<p style=\"text-align: justify;\"><span>Saia dos ciclos de intensidade e desorganiza\u00e7\u00e3o e passe a operar com regularidade. Mesmo nos dias dif\u00edceis, voc\u00ea executa o que precisa ser feito.<\/span><\/p>\n<p>[\/et_pb_blurb][\/et_pb_column][et_pb_column type=&#8221;1_4&#8243; _builder_version=&#8221;4.16&#8243; background_color=&#8221;#d0d6db&#8221; use_background_color_gradient=&#8221;on&#8221; background_color_gradient_stops=&#8221;#ffd088 0%|#ffc882 70%&#8221; background_color_gradient_start=&#8221;#ffd088&#8243; background_color_gradient_end=&#8221;#ffc882&#8243; background_color_gradient_end_position=&#8221;70%&#8221; custom_padding=&#8221;60px|40px|150px|40px&#8221; custom_padding_tablet=&#8221;60px|||&#8221; custom_padding_phone=&#8221;60px||60px||true&#8221; custom_padding_last_edited=&#8221;on|phone&#8221; global_colors_info=&#8221;{}&#8221; padding_phone=&#8221;60px||60px||true&#8221; padding_tablet=&#8221;60px|||&#8221; padding_last_edited=&#8221;on|phone&#8221; custom_padding__hover=&#8221;|||&#8221;][et_pb_blurb title=&#8221;Estabilidade&#8221; use_icon=&#8221;on&#8221; font_icon=&#8221;&#xe089;||divi||400&#8243; icon_color=&#8221;#345168&#8243; image_icon_width=&#8221;32px&#8221; _builder_version=&#8221;4.27.4&#8243; header_level=&#8221;h3&#8243; header_font=&#8221;Lato|700|||||||&#8221; header_line_height=&#8221;1.5em&#8221; body_font=&#8221;Lato||||||||&#8221; body_font_size=&#8221;18px&#8221; body_line_height=&#8221;1.8em&#8221; text_orientation=&#8221;center&#8221; background_layout=&#8221;dark&#8221; max_width=&#8221;340px&#8221; module_alignment=&#8221;center&#8221; custom_margin=&#8221;||30px|&#8221; animation_style=&#8221;slide&#8221; animation_direction=&#8221;bottom&#8221; animation_delay=&#8221;200ms&#8221; animation_intensity_slide=&#8221;5%&#8221; icon_font_size=&#8221;32px&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<p style=\"text-align: justify;\"><span>Reduza o ru\u00eddo mental, o estresse e os conflitos internos. Suas decis\u00f5es se tornam mais firmes, e sua fam\u00edlia sente seguran\u00e7a na sua postura.<\/span><\/p>\n<p>[\/et_pb_blurb][\/et_pb_column][et_pb_column type=&#8221;1_4&#8243; _builder_version=&#8221;4.16&#8243; background_color=&#8221;#d9dfe4&#8243; use_background_color_gradient=&#8221;on&#8221; background_color_gradient_stops=&#8221;#ffd088 0%|#ffd6a0 70%&#8221; background_color_gradient_start=&#8221;#ffd088&#8243; background_color_gradient_end=&#8221;#ffd6a0&#8243; background_color_gradient_end_position=&#8221;70%&#8221; custom_padding=&#8221;50px|40px|150px|40px&#8221; custom_padding_tablet=&#8221;60px|||&#8221; custom_padding_phone=&#8221;60px|||&#8221; custom_padding_last_edited=&#8221;on|phone&#8221; global_colors_info=&#8221;{}&#8221; padding_phone=&#8221;60px|||&#8221; padding_tablet=&#8221;60px|||&#8221; padding_last_edited=&#8221;on|phone&#8221; custom_padding__hover=&#8221;|||&#8221;][et_pb_blurb title=&#8221;Progresso&#8221; use_icon=&#8221;on&#8221; font_icon=&#8221;&#xe085;||divi||400&#8243; icon_color=&#8221;#345168&#8243; image_icon_width=&#8221;32px&#8221; _builder_version=&#8221;4.27.4&#8243; header_level=&#8221;h3&#8243; header_font=&#8221;Lato|700|||||||&#8221; header_line_height=&#8221;1.5em&#8221; body_font=&#8221;Lato||||||||&#8221; body_font_size=&#8221;18px&#8221; body_line_height=&#8221;1.8em&#8221; text_orientation=&#8221;center&#8221; background_layout=&#8221;dark&#8221; max_width=&#8221;340px&#8221; module_alignment=&#8221;center&#8221; custom_margin=&#8221;||30px|&#8221; animation_style=&#8221;slide&#8221; animation_direction=&#8221;bottom&#8221; animation_delay=&#8221;300ms&#8221; animation_intensity_slide=&#8221;5%&#8221; icon_font_size=&#8221;32px&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<p style=\"text-align: justify;\"><span>Voc\u00ea come\u00e7a a concluir o que inicia. Cada entrega concreta fortalece sua confian\u00e7a e cria avan\u00e7o real na carreira, nos projetos e na vida pessoal.<\/span><\/p>\n<p>[\/et_pb_blurb][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8221;1&#8243; admin_label=&#8221;What Is Coaching?&#8221; _builder_version=&#8221;4.27.4&#8243; custom_padding=&#8221;|||&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_row column_structure=&#8221;1_2,1_2&#8243; _builder_version=&#8221;4.16&#8243; max_width=&#8221;1280px&#8221; animation_direction=&#8221;bottom&#8221; use_custom_width=&#8221;on&#8221; custom_width_px=&#8221;1280px&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;1_2&#8243; _builder_version=&#8221;4.16&#8243; custom_padding=&#8221;|||&#8221; global_colors_info=&#8221;{}&#8221; custom_padding__hover=&#8221;|||&#8221;][et_pb_text admin_label=&#8221;Text&#8221; _builder_version=&#8221;4.27.4&#8243; text_font=&#8221;Lato||||||||&#8221; text_font_size=&#8221;18px&#8221; text_line_height=&#8221;1.8em&#8221; link_font=&#8221;||||||||&#8221; ul_font=&#8221;||||||||&#8221; ol_font=&#8221;||||||||&#8221; quote_font=&#8221;||||||||&#8221; header_font=&#8221;||||||||&#8221; header_2_font=&#8221;Lato|700|||||||&#8221; header_2_font_size=&#8221;40px&#8221; header_2_letter_spacing=&#8221;1px&#8221; header_2_line_height=&#8221;1.5em&#8221; header_3_font=&#8221;||||||||&#8221; header_4_font=&#8221;||||||||&#8221; header_5_font=&#8221;||||||||&#8221; header_6_font=&#8221;Lato|700|||||||&#8221; header_6_font_size=&#8221;18px&#8221; header_6_letter_spacing=&#8221;1px&#8221; header_6_line_height=&#8221;1.8em&#8221; text_orientation=&#8221;right&#8221; animation_style=&#8221;slide&#8221; animation_direction=&#8221;bottom&#8221; animation_intensity_slide=&#8221;5%&#8221; header_2_font_size_tablet=&#8221;&#8221; header_2_font_size_phone=&#8221;22px&#8221; header_2_font_size_last_edited=&#8221;on|phone&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<h6><span>Conquiste seus objetivos com uma consultoria <\/span><strong data-start=\"45\" data-end=\"70\">de estrat\u00e9gia pessoal<\/strong><span>.<\/span><\/h6>\n<h2 style=\"text-align: left;\"><span>Sente que <\/span><strong data-start=\"10\" data-end=\"18\">est\u00e1<\/strong><span> na hora de fazer uma mudan\u00e7a, mas <\/span><strong data-start=\"53\" data-end=\"60\">n\u00e3o<\/strong><span> consegue encontrar o caminho?<\/span><\/h2>\n<p style=\"text-align: justify;\">Se voc\u00ea \u00e9 altamente capaz, mas sente que est\u00e1 sempre aqu\u00e9m do seu pr\u00f3prio potencial, minha consultoria \u00e9 o ponto de virada. <strong>Nao forne\u00e7o servi\u00e7os de terapia<\/strong>, eu ajudo voc\u00ea a organizar sua vida com clareza estrat\u00e9gica, criar um sistema de execu\u00e7\u00e3o consistente e gerar resultados vis\u00edveis \u2014 na carreira, na fam\u00edlia e nos seus projetos pessoais. Voc\u00ea n\u00e3o vai sair apenas motivado; vai sair com dire\u00e7\u00e3o, estrutura e um plano pr\u00e1tico que funciona na vida real. Se est\u00e1 pronto para parar de come\u00e7ar e finalmente come\u00e7ar a concluir, eu posso te mostrar o caminho.<\/p>\n<p>[\/et_pb_text][et_pb_code _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;]<div class=\"latepoint-book-button-wrapper wp-block-button\"><a href=\"#\" class=\"latepoint-book-button os_trigger_booking wp-block-button__link\" style=\"background-color: #ffb356; color: #ffffff\" >Agendar Sess\u00e3o<\/a><\/div>[\/et_pb_code][\/et_pb_column][et_pb_column type=&#8221;1_2&#8243; _builder_version=&#8221;4.16&#8243; custom_padding=&#8221;80px|||&#8221; global_colors_info=&#8221;{}&#8221; custom_padding__hover=&#8221;|||&#8221;][et_pb_text _builder_version=&#8221;4.16&#8243; text_font=&#8221;Lato||||||||&#8221; text_font_size=&#8221;18px&#8221; text_line_height=&#8221;1.8em&#8221; link_font=&#8221;||||||||&#8221; ul_font=&#8221;||||||||&#8221; ol_font=&#8221;||||||||&#8221; quote_font=&#8221;||||||||&#8221; header_font=&#8221;||||||||&#8221; header_2_font=&#8221;Lato|700|||||||&#8221; header_2_font_size=&#8221;30px&#8221; header_2_letter_spacing=&#8221;1px&#8221; header_2_line_height=&#8221;1.5em&#8221; animation_style=&#8221;slide&#8221; animation_direction=&#8221;bottom&#8221; animation_intensity_slide=&#8221;5%&#8221; header_2_font_size_tablet=&#8221;&#8221; header_2_font_size_phone=&#8221;22px&#8221; header_2_font_size_last_edited=&#8221;on|phone&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<h2>Como a consultoria funciona?<\/h2>\n<p>[\/et_pb_text][et_pb_blurb title=&#8221;Voc\u00ea est\u00e1 confuso sobre o que realmente deveria priorizar?&#8221; use_icon=&#8221;on&#8221; font_icon=&#8221;&#xe052;||divi||400&#8243; icon_color=&#8221;#ffb356&#8243; icon_placement=&#8221;left&#8221; image_icon_width=&#8221;22px&#8221; content_max_width=&#8221;1100px&#8221; _builder_version=&#8221;4.27.4&#8243; header_font=&#8221;Lato|700|||||||&#8221; header_font_size=&#8221;16px&#8221; header_line_height=&#8221;1.4em&#8221; body_font=&#8221;||||||||&#8221; custom_margin=&#8221;|||&#8221; animation_style=&#8221;slide&#8221; animation_direction=&#8221;bottom&#8221; animation_intensity_slide=&#8221;5%&#8221; icon_font_size=&#8221;22px&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<p style=\"text-align: justify;\"><span>Na consultoria, voc\u00ea ganha clareza estrat\u00e9gica sobre sua realidade, identifica padr\u00f5es de pensamento, obst\u00e1culos e oportunidades, e passa a tomar decis\u00f5es com dire\u00e7\u00e3o e seguran\u00e7a.<\/span><\/p>\n<p>[\/et_pb_blurb][et_pb_blurb title=&#8221;Sua mente \u00e9 inquieta e voc\u00ea vive em ciclos de desorganiza\u00e7\u00e3o?&#8221; use_icon=&#8221;on&#8221; font_icon=&#8221;&#xe052;||divi||400&#8243; icon_color=&#8221;#ffb356&#8243; icon_placement=&#8221;left&#8221; image_icon_width=&#8221;22px&#8221; content_max_width=&#8221;1100px&#8221; _builder_version=&#8221;4.27.4&#8243; header_font=&#8221;Lato|700|||||||&#8221; header_font_size=&#8221;16px&#8221; header_line_height=&#8221;1.4em&#8221; body_font=&#8221;||||||||&#8221; custom_margin=&#8221;|||&#8221; animation_style=&#8221;slide&#8221; animation_direction=&#8221;bottom&#8221; animation_intensity_slide=&#8221;5%&#8221; icon_font_size=&#8221;22px&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<p style=\"text-align: justify;\"><span>Eu ajudo voc\u00ea a entender seus gatilhos, reduzir atritos internos e estruturar sua forma de pensar para acelerar decis\u00f5es e transformar inquieta\u00e7\u00e3o em foco produtivo.<\/span><\/p>\n<p>[\/et_pb_blurb][et_pb_blurb title=&#8221;Voc\u00ea come\u00e7a metas, mas n\u00e3o consegue conclu\u00ed-las?&#8221; use_icon=&#8221;on&#8221; font_icon=&#8221;&#xe052;||divi||400&#8243; icon_color=&#8221;#ffb356&#8243; icon_placement=&#8221;left&#8221; image_icon_width=&#8221;22px&#8221; content_max_width=&#8221;1100px&#8221; _builder_version=&#8221;4.27.4&#8243; header_font=&#8221;Lato|700|||||||&#8221; header_font_size=&#8221;16px&#8221; header_line_height=&#8221;1.4em&#8221; body_font=&#8221;||||||||&#8221; custom_margin=&#8221;|||&#8221; animation_style=&#8221;slide&#8221; animation_direction=&#8221;bottom&#8221; animation_intensity_slide=&#8221;5%&#8221; icon_font_size=&#8221;22px&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<p style=\"text-align: justify;\"><span>Aprenda a definir objetivos espec\u00edficos, com prazos realistas e estrat\u00e9gia de execu\u00e7\u00e3o, eliminando confus\u00e3o, procrastina\u00e7\u00e3o e autossabotagem.<\/span><\/p>\n<p>[\/et_pb_blurb][et_pb_blurb title=&#8221;Voc\u00ea tem dificuldade de sustentar a rotina?&#8221; use_icon=&#8221;on&#8221; font_icon=&#8221;&#xe052;||divi||400&#8243; icon_color=&#8221;#ffb356&#8243; icon_placement=&#8221;left&#8221; image_icon_width=&#8221;22px&#8221; content_max_width=&#8221;1100px&#8221; _builder_version=&#8221;4.27.4&#8243; header_font=&#8221;Lato|700|||||||&#8221; header_font_size=&#8221;16px&#8221; header_line_height=&#8221;1.4em&#8221; body_font=&#8221;||||||||&#8221; custom_margin=&#8221;|||&#8221; animation_style=&#8221;slide&#8221; animation_direction=&#8221;bottom&#8221; animation_intensity_slide=&#8221;5%&#8221; icon_font_size=&#8221;22px&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<p style=\"text-align: justify;\"><span>Constru\u00edmos uma rotina m\u00ednima vi\u00e1vel, com h\u00e1bitos mensur\u00e1veis e acompanhamento estrat\u00e9gico, para gerar const\u00e2ncia sem depender de motiva\u00e7\u00e3o.<\/span><\/p>\n<p>[\/et_pb_blurb][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8221;1&#8243; prev_background_color=&#8221;#ffffff&#8221; next_background_color=&#8221;#f5f5f5&#8243; admin_label=&#8221;Who Is Coaching For?&#8221; _builder_version=&#8221;4.27.4&#8243; background_color=&#8221;RGBA(255,255,255,0)&#8221; use_background_color_gradient=&#8221;on&#8221; background_color_gradient_stops=&#8221;#345168 5%|rgba(219,219,219,0) 100%&#8221; background_color_gradient_overlays_image=&#8221;on&#8221; background_color_gradient_start=&#8221;#345168&#8243; background_color_gradient_start_position=&#8221;5%&#8221; background_color_gradient_end=&#8221;rgba(219,219,219,0)&#8221; background_image=&#8221;https:\/\/a2byourself.com\/wp-content\/uploads\/2025\/10\/life-coach-34.jpg&#8221; custom_padding=&#8221;150px||150px||true|false&#8221; top_divider_style=&#8221;slant&#8221; top_divider_flip=&#8221;horizontal&#8221; bottom_divider_style=&#8221;slant&#8221; bottom_divider_flip=&#8221;horizontal&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_row column_structure=&#8221;1_2,1_2&#8243; _builder_version=&#8221;4.16&#8243; use_custom_width=&#8221;on&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;1_2&#8243; _builder_version=&#8221;4.16&#8243; custom_padding=&#8221;|||&#8221; global_colors_info=&#8221;{}&#8221; custom_padding__hover=&#8221;|||&#8221;][et_pb_text admin_label=&#8221;Text&#8221; _builder_version=&#8221;4.27.4&#8243; text_font=&#8221;Lato||||||||&#8221; text_font_size=&#8221;18px&#8221; text_line_height=&#8221;1.8em&#8221; link_font=&#8221;||||||||&#8221; ul_font=&#8221;||||||||&#8221; ol_font=&#8221;||||||||&#8221; quote_font=&#8221;||||||||&#8221; header_font=&#8221;||||||||&#8221; header_2_font=&#8221;Lato|700|||||||&#8221; header_2_font_size=&#8221;40px&#8221; header_2_letter_spacing=&#8221;1px&#8221; header_2_line_height=&#8221;1.5em&#8221; header_3_font=&#8221;||||||||&#8221; header_4_font=&#8221;||||||||&#8221; header_5_font=&#8221;||||||||&#8221; header_6_font=&#8221;Lato|700|||||||&#8221; header_6_font_size=&#8221;18px&#8221; header_6_letter_spacing=&#8221;1px&#8221; header_6_line_height=&#8221;1.8em&#8221; text_orientation=&#8221;right&#8221; background_layout=&#8221;dark&#8221; header_2_font_size_tablet=&#8221;&#8221; header_2_font_size_phone=&#8221;22px&#8221; header_2_font_size_last_edited=&#8221;on|phone&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<h2><span>Voc\u00ea realmente precisa de uma consultoria?<\/span><\/h2>\n<p style=\"text-align: justify;\">A consultoria \u00e9 perfeita para pessoas funcionais, cumprem o que precisa ser feito e sabem que tem potencial para mais, mas n\u00e3o conseguem manter const\u00e2ncia, disciplina e controle sobre a pr\u00f3pria mente e comportamento. Se voce est\u00e1 cansado(a) de depender de motiva\u00e7\u00e3o e picos de energia para produzir, aqui voc\u00ea constr\u00f3i sistemas claros, rotina estruturada e dire\u00e7\u00e3o estrat\u00e9gica para gerar estabilidade e progresso real no longo prazo.<\/p>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=&#8221;1_2&#8243; _builder_version=&#8221;4.16&#8243; custom_padding=&#8221;|||&#8221; global_colors_info=&#8221;{}&#8221; custom_padding__hover=&#8221;|||&#8221;][et_pb_toggle title=&#8221;Voc\u00ea se distrai e perde o foco com facilidade.&#8221; open_toggle_background_color=&#8221;#ccd8e5&#8243; closed_toggle_background_color=&#8221;#ccd8e5&#8243; icon_color=&#8221;#345168&#8243; open_icon_color=&#8221;#345168&#8243; _builder_version=&#8221;4.27.4&#8243; title_font=&#8221;Lato|700|||||||&#8221; title_line_height=&#8221;1.5em&#8221; body_font=&#8221;||||||||&#8221; body_font_size=&#8221;16px&#8221; body_line_height=&#8221;2em&#8221; custom_margin=&#8221;||0px|&#8221; animation_style=&#8221;slide&#8221; animation_direction=&#8221;top&#8221; animation_intensity_slide=&#8221;10%&#8221; border_width_all=&#8221;0px&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<p>Se distra\u00e7\u00f5es te puxam de um lado para o outro e voc\u00ea tem dificuldade de manter o foco nas tarefas do presente e nos objetivos de longo prazo, a consultoria oferece a estrutura que est\u00e1 faltando. Voc\u00ea organiza suas prioridades, reduz o ru\u00eddo mental e constr\u00f3i sistemas que sustentam const\u00e2ncia e progresso real \u2014 sem depender de motiva\u00e7\u00e3o para agir.<\/p>\n<p>[\/et_pb_toggle][et_pb_toggle title=&#8221;Sua mente \u00e9 potente, mas falta dire\u00e7\u00e3o estrat\u00e9gica.&#8221; open_toggle_background_color=&#8221;#dae1ed&#8221; closed_toggle_background_color=&#8221;#dae1ed&#8221; icon_color=&#8221;#345168&#8243; open_icon_color=&#8221;#345168&#8243; _builder_version=&#8221;4.27.4&#8243; title_font=&#8221;Lato|700|||||||&#8221; title_line_height=&#8221;1.5em&#8221; body_font=&#8221;||||||||&#8221; body_font_size=&#8221;16px&#8221; body_line_height=&#8221;2em&#8221; custom_margin=&#8221;||0px|&#8221; animation_style=&#8221;slide&#8221; animation_direction=&#8221;top&#8221; animation_intensity_slide=&#8221;10%&#8221; border_width_all=&#8221;0px&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<p>Sua mente \u00e9 potente \u2014 ela s\u00f3 precisa de dire\u00e7\u00e3o estrat\u00e9gica. Voc\u00ea n\u00e3o precisa silenci\u00e1-la, mas canalizar sua energia e agir com prioridades claras.<\/p>\n<p>[\/et_pb_toggle][et_pb_toggle title=&#8221;Voc\u00ea tem dificuldade em manter uma rotina m\u00ednima vi\u00e1vel.&#8221; open_toggle_background_color=&#8221;#e3e9ef&#8221; closed_toggle_background_color=&#8221;#e3e9ef&#8221; icon_color=&#8221;#345168&#8243; open_icon_color=&#8221;#345168&#8243; _builder_version=&#8221;4.27.4&#8243; title_font=&#8221;Lato|700|||||||&#8221; title_line_height=&#8221;1.5em&#8221; body_font=&#8221;||||||||&#8221; body_font_size=&#8221;16px&#8221; body_line_height=&#8221;2em&#8221; custom_margin=&#8221;||0px|&#8221; animation_style=&#8221;slide&#8221; animation_direction=&#8221;top&#8221; animation_intensity_slide=&#8221;10%&#8221; border_width_all=&#8221;0px&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<p>Muitas pessoas se perdem em rotinas complexas e sem dire\u00e7\u00e3o clara. A consultoria simplifica sua estrutura at\u00e9 que a execu\u00e7\u00e3o se torne natural, objetiva e praticamente inevit\u00e1vel.<\/p>\n<p>[\/et_pb_toggle][et_pb_toggle title=&#8221;Voc\u00ea oscila entre foco intenso e desorganiza\u00e7\u00e3o.&#8221; open_toggle_background_color=&#8221;#edf0f7&#8243; closed_toggle_background_color=&#8221;#edf0f7&#8243; icon_color=&#8221;#345168&#8243; open_icon_color=&#8221;#345168&#8243; _builder_version=&#8221;4.27.4&#8243; title_font=&#8221;Lato|700|||||||&#8221; title_line_height=&#8221;1.5em&#8221; body_font=&#8221;||||||||&#8221; body_font_size=&#8221;16px&#8221; body_line_height=&#8221;2em&#8221; custom_margin=&#8221;||0px|&#8221; animation_style=&#8221;slide&#8221; animation_direction=&#8221;top&#8221; animation_intensity_slide=&#8221;10%&#8221; border_width_all=&#8221;0px&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<p>Voc\u00ea vive o ciclo cl\u00e1ssico \u201cpico \u2013 queda \u2013 culpa \u2013 rein\u00edcio\u201d? Se sim, juntos construiremos rituais fixos, metas alcan\u00e7\u00e1veis e revis\u00f5es semanais para transformar intensidade em const\u00e2ncia.<\/p>\n<p>[\/et_pb_toggle][et_pb_toggle title=&#8221;Voc\u00ea n\u00e3o tem um sistema estruturado.&#8221; open_toggle_background_color=&#8221;#f4f7fc&#8221; closed_toggle_background_color=&#8221;#f4f7fc&#8221; icon_color=&#8221;#345168&#8243; open_icon_color=&#8221;#345168&#8243; _builder_version=&#8221;4.27.4&#8243; title_font=&#8221;Lato|700|||||||&#8221; title_line_height=&#8221;1.5em&#8221; body_font=&#8221;||||||||&#8221; body_font_size=&#8221;16px&#8221; body_line_height=&#8221;2em&#8221; custom_margin=&#8221;||0px|&#8221; animation_style=&#8221;slide&#8221; animation_direction=&#8221;top&#8221; animation_intensity_slide=&#8221;10%&#8221; border_width_all=&#8221;0px&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<p>Sem sistema, tudo vira urg\u00eancia \u2014 ou nada recebe a aten\u00e7\u00e3o necess\u00e1ria. Com estrutura clara, cada dia tem prop\u00f3sito, e \u00e9 a sua agenda, n\u00e3o seus impulsos, que passa a conduzir sua vida.<\/p>\n<p>[\/et_pb_toggle][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8221;1&#8243; admin_label=&#8221;Approach&#8221; _builder_version=&#8221;4.27.4&#8243; background_color=&#8221;#f5f5f5&#8243; custom_padding=&#8221;0px|0px|0|0px|false|false&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_row column_structure=&#8221;1_2,1_2&#8243; use_custom_gutter=&#8221;on&#8221; gutter_width=&#8221;1&#8243; _builder_version=&#8221;4.16&#8243; min_height=&#8221;709.6px&#8221; custom_margin=&#8221;|||&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;1_2&#8243; _builder_version=&#8221;4.16&#8243; custom_padding=&#8221;|||&#8221; custom_padding_tablet=&#8221;|40px||40px||true&#8221; custom_padding_last_edited=&#8221;off|desktop&#8221; global_colors_info=&#8221;{}&#8221; padding_tablet=&#8221;|40px||40px||true&#8221; padding_last_edited=&#8221;off|desktop&#8221; custom_padding__hover=&#8221;|||&#8221;][et_pb_text _builder_version=&#8221;4.27.4&#8243; text_font=&#8221;Lato||||||||&#8221; text_font_size=&#8221;18px&#8221; text_line_height=&#8221;1.8em&#8221; link_font=&#8221;||||||||&#8221; ul_font=&#8221;||||||||&#8221; ol_font=&#8221;||||||||&#8221; quote_font=&#8221;||||||||&#8221; header_font=&#8221;||||||||&#8221; header_2_font=&#8221;Lato|700|||||||&#8221; header_2_font_size=&#8221;40px&#8221; header_2_letter_spacing=&#8221;1px&#8221; header_2_line_height=&#8221;1.5em&#8221; header_3_font=&#8221;||||||||&#8221; header_4_font=&#8221;||||||||&#8221; header_5_font=&#8221;||||||||&#8221; header_6_font=&#8221;Lato|700|||||||&#8221; header_6_font_size=&#8221;18px&#8221; header_6_letter_spacing=&#8221;1px&#8221; header_6_line_height=&#8221;1.8em&#8221; background_color=&#8221;#ffffff&#8221; custom_margin=&#8221;20px||||false|false&#8221; custom_margin_tablet=&#8221;0px|0px|0px|&#8221; custom_margin_phone=&#8221;&#8221; custom_margin_last_edited=&#8221;on|phone&#8221; custom_padding=&#8221;40px|40px|40px|40px|true|true&#8221; custom_padding_tablet=&#8221;|40px||40px||true&#8221; custom_padding_last_edited=&#8221;off|desktop&#8221; animation_style=&#8221;slide&#8221; animation_direction=&#8221;bottom&#8221; animation_intensity_slide=&#8221;5%&#8221; header_2_font_size_tablet=&#8221;&#8221; header_2_font_size_phone=&#8221;22px&#8221; header_2_font_size_last_edited=&#8221;on|phone&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<h2>Minha abordagem.<\/h2>\n<p>Eu ajudo pessoas altamente capazes a sa\u00edrem da inconsist\u00eancia e entrarem em execu\u00e7\u00e3o real. Minha abordagem em estrat\u00e9gia pessoal \u00e9 direta, pr\u00e1tica e orientada a resultado. N\u00e3o trabalho com motiva\u00e7\u00e3o passageira \u2014 construo sistemas simples que organizam sua rotina, clarificam suas prioridades e eliminam o caos que drena sua energia. Com princ\u00edpios bem definidos e m\u00e9tricas claras, voc\u00ea reduz o estresse, toma decis\u00f5es com seguran\u00e7a e volta a confiar em si mesmo.<\/p>\n<p>Unindo minha forma\u00e7\u00e3o em Psicologia no Canad\u00e1, experi\u00eancia em lideran\u00e7a de equipes de alta performance e viv\u00eancia como marido, pai e empreendedor, desenvolvi um m\u00e9todo aplic\u00e1vel \u00e0 vida real. Voc\u00ea n\u00e3o precisa produzir mais esfor\u00e7o \u2014 precisa de dire\u00e7\u00e3o e estrutura. O resultado? Mais foco, mais const\u00e2ncia, mais respeito dentro de casa e mais progresso concreto na carreira e nos projetos que realmente importam.<\/p>\n<p>[\/et_pb_text][et_pb_code _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;]<div class=\"latepoint-book-button-wrapper wp-block-button\"><a href=\"#\" class=\"latepoint-book-button os_trigger_booking wp-block-button__link\" style=\"background-color: #ffb356; color: #ffffff\" >Agendar Sess\u00e3o<\/a><\/div>[\/et_pb_code][\/et_pb_column][et_pb_column type=&#8221;1_2&#8243; _builder_version=&#8221;4.16&#8243; custom_padding=&#8221;|||&#8221; global_colors_info=&#8221;{}&#8221; custom_padding__hover=&#8221;|||&#8221;][et_pb_image src=&#8221;https:\/\/a2byourself.com\/wp-content\/uploads\/2026\/03\/WhatsApp-Image-2026-03-08-at-18.39.36-2.webp&#8221; title_text=&#8221;WhatsApp-Image-2026-03-08-at-18.39.36-2.webp&#8221; align_tablet=&#8221;center&#8221; align_phone=&#8221;center&#8221; align_last_edited=&#8221;on|desktop&#8221; _builder_version=&#8221;4.27.4&#8243; width=&#8221;80%&#8221; custom_margin=&#8221;|||&#8221; custom_margin_tablet=&#8221;0px|0px|0px|0px|true|true&#8221; custom_margin_last_edited=&#8221;off|desktop&#8221; animation_style=&#8221;slide&#8221; animation_direction=&#8221;top&#8221; animation_intensity_slide=&#8221;5%&#8221; animation=&#8221;top&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_image][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8221;1&#8243; next_background_color=&#8221;RGBA(255,255,255,0)&#8221; admin_label=&#8221;How It Works&#8221; _builder_version=&#8221;4.27.4&#8243; background_color=&#8221;#ffffff&#8221; use_background_color_gradient=&#8221;on&#8221; background_color_gradient_stops=&#8221;#f5f5f5 0%|#ffffff 100%&#8221; background_color_gradient_start=&#8221;#f5f5f5&#8243; background_color_gradient_end=&#8221;#ffffff&#8221; custom_padding=&#8221;0px|0px|0|0px|false|false&#8221; bottom_divider_style=&#8221;slant&#8221; bottom_divider_flip=&#8221;horizontal&#8221; bottom_divider_arrangement=&#8221;above_content&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_row _builder_version=&#8221;4.16&#8243; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.16&#8243; custom_padding=&#8221;|||&#8221; global_colors_info=&#8221;{}&#8221; custom_padding__hover=&#8221;|||&#8221;][et_pb_text admin_label=&#8221;Text&#8221; _builder_version=&#8221;4.27.4&#8243; text_font=&#8221;Lato||||||||&#8221; text_font_size=&#8221;18px&#8221; text_line_height=&#8221;1.8em&#8221; link_font=&#8221;||||||||&#8221; ul_font=&#8221;||||||||&#8221; ol_font=&#8221;||||||||&#8221; quote_font=&#8221;||||||||&#8221; header_font=&#8221;||||||||&#8221; header_2_font=&#8221;Lato|700|||||||&#8221; header_2_font_size=&#8221;40px&#8221; header_2_letter_spacing=&#8221;1px&#8221; header_2_line_height=&#8221;1.5em&#8221; header_3_font=&#8221;||||||||&#8221; header_4_font=&#8221;||||||||&#8221; header_5_font=&#8221;||||||||&#8221; header_6_font=&#8221;Lato|700|||||||&#8221; header_6_font_size=&#8221;18px&#8221; header_6_letter_spacing=&#8221;1px&#8221; header_6_line_height=&#8221;1.8em&#8221; text_orientation=&#8221;center&#8221; animation_style=&#8221;slide&#8221; animation_direction=&#8221;bottom&#8221; animation_intensity_slide=&#8221;5%&#8221; header_2_font_size_tablet=&#8221;&#8221; header_2_font_size_phone=&#8221;22px&#8221; header_2_font_size_last_edited=&#8221;on|phone&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<h2>Como iniciar?<\/h2>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=&#8221;1_3,1_3,1_3&#8243; use_custom_gutter=&#8221;on&#8221; gutter_width=&#8221;1&#8243; make_equal=&#8221;on&#8221; padding_top_bottom_link_1=&#8221;false&#8221; padding_top_bottom_link_2=&#8221;false&#8221; padding_top_bottom_link_3=&#8221;false&#8221; padding_top_bottom_link_4=&#8221;false&#8221; padding_left_right_link_1=&#8221;true&#8221; padding_left_right_link_2=&#8221;true&#8221; padding_left_right_link_3=&#8221;true&#8221; padding_left_right_link_4=&#8221;true&#8221; _builder_version=&#8221;4.16&#8243; custom_margin=&#8221;|||&#8221; custom_padding=&#8221;0px|0px|0|0px|false|false&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;1_3&#8243; _builder_version=&#8221;4.16&#8243; background_color=&#8221;#c4cace&#8221; use_background_color_gradient=&#8221;on&#8221; background_color_gradient_stops=&#8221;#ffd088 0%|#ffb356 70%&#8221; background_color_gradient_start=&#8221;#ffd088&#8243; background_color_gradient_end=&#8221;#ffb356&#8243; background_color_gradient_end_position=&#8221;70%&#8221; custom_padding=&#8221;60px|40px|150px|40px&#8221; custom_padding_tablet=&#8221;20px||60px|&#8221; custom_padding_phone=&#8221;60px||60px||true&#8221; custom_padding_last_edited=&#8221;on|tablet&#8221; global_colors_info=&#8221;{}&#8221; padding_phone=&#8221;60px||60px||true&#8221; padding_tablet=&#8221;20px||60px|&#8221; padding_last_edited=&#8221;on|tablet&#8221; custom_padding__hover=&#8221;|||&#8221;][et_pb_blurb title=&#8221;Agende sua sess\u00e3o Inicial.&#8221; use_icon=&#8221;on&#8221; font_icon=&#8221;&#xe08b;||divi||400&#8243; icon_color=&#8221;#345168&#8243; image_icon_width=&#8221;32px&#8221; _builder_version=&#8221;4.16&#8243; header_level=&#8221;h3&#8243; header_font=&#8221;Lato|700|||||||&#8221; header_line_height=&#8221;1.5em&#8221; body_font=&#8221;Lato||||||||&#8221; body_font_size=&#8221;18px&#8221; body_line_height=&#8221;1.8em&#8221; text_orientation=&#8221;center&#8221; background_layout=&#8221;dark&#8221; max_width=&#8221;340px&#8221; module_alignment=&#8221;center&#8221; custom_margin=&#8221;|||&#8221; animation_style=&#8221;slide&#8221; animation_direction=&#8221;bottom&#8221; animation_intensity_slide=&#8221;5%&#8221; icon_font_size=&#8221;32px&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<p><span>Agende sua Avaliacao Estrat\u00e9gica Inicial e descubra exatamente onde voc\u00ea est\u00e1 e o que precisa ajustar para avan\u00e7ar.<\/span><\/p>\n<p>[\/et_pb_blurb][\/et_pb_column][et_pb_column type=&#8221;1_3&#8243; _builder_version=&#8221;4.16&#8243; background_color=&#8221;#cbd0d6&#8243; use_background_color_gradient=&#8221;on&#8221; background_color_gradient_stops=&#8221;#ffd088 0%|#ffbe6b 70%&#8221; background_color_gradient_start=&#8221;#ffd088&#8243; background_color_gradient_end=&#8221;#ffbe6b&#8221; background_color_gradient_end_position=&#8221;70%&#8221; custom_padding=&#8221;60px|40px|150px|40px&#8221; custom_padding_tablet=&#8221;20px||60px|&#8221; custom_padding_phone=&#8221;60px||60px||true&#8221; custom_padding_last_edited=&#8221;on|desktop&#8221; global_colors_info=&#8221;{}&#8221; padding_phone=&#8221;60px||60px||true&#8221; padding_tablet=&#8221;20px||60px|&#8221; padding_last_edited=&#8221;on|desktop&#8221; custom_padding__hover=&#8221;|||&#8221;][et_pb_blurb title=&#8221;Escolha um dos planos.&#8221; use_icon=&#8221;on&#8221; font_icon=&#8221;&#x69;||divi||400&#8243; icon_color=&#8221;#345168&#8243; image_icon_width=&#8221;32px&#8221; _builder_version=&#8221;4.16&#8243; header_level=&#8221;h3&#8243; header_font=&#8221;Lato|700|||||||&#8221; header_line_height=&#8221;1.5em&#8221; body_font=&#8221;Lato||||||||&#8221; body_font_size=&#8221;18px&#8221; body_line_height=&#8221;1.8em&#8221; text_orientation=&#8221;center&#8221; background_layout=&#8221;dark&#8221; max_width=&#8221;340px&#8221; module_alignment=&#8221;center&#8221; custom_margin=&#8221;|||&#8221; animation_style=&#8221;slide&#8221; animation_direction=&#8221;bottom&#8221; animation_intensity_slide=&#8221;5%&#8221; icon_font_size=&#8221;32px&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<p><span>Com base nas avalia\u00e7\u00f5es iniciais, escolha o pacote de acordo com o n\u00edvel de profundidade e transforma\u00e7\u00e3o que voc\u00ea deseja alcan\u00e7ar.<\/span><\/p>\n<p>[\/et_pb_blurb][\/et_pb_column][et_pb_column type=&#8221;1_3&#8243; _builder_version=&#8221;4.16&#8243; background_color=&#8221;#d0d6db&#8221; use_background_color_gradient=&#8221;on&#8221; background_color_gradient_stops=&#8221;#ffd088 0%|#ffc882 70%&#8221; background_color_gradient_start=&#8221;#ffd088&#8243; background_color_gradient_end=&#8221;#ffc882&#8243; background_color_gradient_end_position=&#8221;70%&#8221; custom_padding=&#8221;60px|40px|150px|40px&#8221; custom_padding_tablet=&#8221;20px|||&#8221; custom_padding_phone=&#8221;60px||||false&#8221; custom_padding_last_edited=&#8221;on|desktop&#8221; global_colors_info=&#8221;{}&#8221; padding_phone=&#8221;60px||||false&#8221; padding_tablet=&#8221;20px|||&#8221; padding_last_edited=&#8221;on|desktop&#8221; custom_padding__hover=&#8221;|||&#8221;][et_pb_blurb title=&#8221;Alcance seus Objetivos&#8221; use_icon=&#8221;on&#8221; font_icon=&#8221;&#xe0f5;||divi||400&#8243; icon_color=&#8221;#345168&#8243; image_icon_width=&#8221;32px&#8221; _builder_version=&#8221;4.16&#8243; header_level=&#8221;h3&#8243; header_font=&#8221;Lato|700|||||||&#8221; header_line_height=&#8221;1.5em&#8221; body_font=&#8221;Lato||||||||&#8221; body_font_size=&#8221;18px&#8221; body_line_height=&#8221;1.8em&#8221; text_orientation=&#8221;center&#8221; background_layout=&#8221;dark&#8221; max_width=&#8221;340px&#8221; module_alignment=&#8221;center&#8221; custom_margin=&#8221;|||&#8221; animation_style=&#8221;slide&#8221; animation_direction=&#8221;bottom&#8221; animation_intensity_slide=&#8221;5%&#8221; icon_font_size=&#8221;32px&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<p>Planeje, execute, me\u00e7a e ajuste seus objetivos desde a primeira sess\u00e3o \u2014 e retome o controle da sua vida com dire\u00e7\u00e3o e estrat\u00e9gia.<\/p>\n<p>[\/et_pb_blurb][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8221;1&#8243; next_background_color=&#8221;#FFFFFF&#8221; admin_label=&#8221;Pricing Packages&#8221; _builder_version=&#8221;4.27.4&#8243; background_color=&#8221;RGBA(255,255,255,0)&#8221; custom_padding=&#8221;||150px|&#8221; bottom_divider_style=&#8221;slant&#8221; bottom_divider_flip=&#8221;horizontal&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_row column_structure=&#8221;3_4,1_4&#8243; admin_label=&#8221;Pricing&#8221; _builder_version=&#8221;4.16&#8243; background_color=&#8221;#ffffff&#8221; max_width=&#8221;900px&#8221; custom_margin=&#8221;|||&#8221; custom_padding=&#8221;30px|30px|30px|30px|true|true&#8221; border_radii=&#8221;on|3px|3px|3px|3px&#8221; use_custom_width=&#8221;on&#8221; custom_width_px=&#8221;900px&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;3_4&#8243; _builder_version=&#8221;4.16&#8243; custom_padding=&#8221;|||&#8221; global_colors_info=&#8221;{}&#8221; custom_padding__hover=&#8221;|||&#8221;][et_pb_text admin_label=&#8221;Package&#8221; _builder_version=&#8221;4.16&#8243; text_font=&#8221;Lato||||||||&#8221; text_font_size=&#8221;18px&#8221; text_line_height=&#8221;1.8em&#8221; header_font=&#8221;||||||||&#8221; header_3_font=&#8221;|700|||||||&#8221; header_3_line_height=&#8221;1.5em&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<h3 data-start=\"75\" data-end=\"95\">Programa Ritmo<\/h3>\n<p data-start=\"96\" data-end=\"191\">Para pessoas que precisam recuperar ou desenvolver const\u00e2ncia e sair do ciclo de desorganiza\u00e7\u00e3o.<\/p>\n<p data-start=\"193\" data-end=\"345\">Aqui voc\u00ea constr\u00f3i disciplina pr\u00e1tica, organiza\u00e7\u00e3o m\u00ednima vi\u00e1vel e execu\u00e7\u00e3o consistente. O foco n\u00e3o \u00e9 fazer mais \u2014 \u00e9 fazer o essencial com regularidade.<\/p>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=&#8221;1_4&#8243; _builder_version=&#8221;4.16&#8243; custom_padding=&#8221;|||&#8221; global_colors_info=&#8221;{}&#8221; custom_padding__hover=&#8221;|||&#8221;][et_pb_code _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;]<div class=\"latepoint-book-button-wrapper wp-block-button\"><a href=\"#\" class=\"latepoint-book-button os_trigger_booking wp-block-button__link\" style=\"background-color: #ffb356; color: #ffffff\" >Quero Ritmo<\/a><\/div>[\/et_pb_code][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=&#8221;4.16&#8243; max_width=&#8221;900px&#8221; custom_margin=&#8221;||40px|&#8221; custom_padding=&#8221;0|0px|0|0px|true|false&#8221; use_custom_width=&#8221;on&#8221; custom_width_px=&#8221;900px&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.16&#8243; custom_padding=&#8221;|||&#8221; global_colors_info=&#8221;{}&#8221; custom_padding__hover=&#8221;|||&#8221;][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=&#8221;3_4,1_4&#8243; admin_label=&#8221;Pricing&#8221; _builder_version=&#8221;4.16&#8243; background_color=&#8221;#ffffff&#8221; max_width=&#8221;900px&#8221; min_height=&#8221;181.2px&#8221; custom_margin=&#8221;-48px|auto||auto||&#8221; custom_padding=&#8221;30px|30px|30px|30px|true|true&#8221; border_radii=&#8221;on|3px|3px|3px|3px&#8221; use_custom_width=&#8221;on&#8221; custom_width_px=&#8221;900px&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;3_4&#8243; _builder_version=&#8221;4.16&#8243; custom_padding=&#8221;|||&#8221; global_colors_info=&#8221;{}&#8221; custom_padding__hover=&#8221;|||&#8221;][et_pb_text admin_label=&#8221;Package&#8221; _builder_version=&#8221;4.16&#8243; text_font=&#8221;Lato||||||||&#8221; text_font_size=&#8221;18px&#8221; text_line_height=&#8221;1.8em&#8221; header_font=&#8221;||||||||&#8221; header_3_font=&#8221;|700|||||||&#8221; header_3_line_height=&#8221;1.5em&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<h3 data-start=\"418\" data-end=\"440\">Programa Clareza<\/h3>\n<p data-start=\"441\" data-end=\"531\">Para quem precisa organizar prioridades e transformar inten\u00e7\u00e3o em planejamento execut\u00e1vel.<\/p>\n<p data-start=\"533\" data-end=\"689\">Aqui estruturamos diagn\u00f3stico, metas estrat\u00e9gicas e um sistema claro de execu\u00e7\u00e3o semanal. Voc\u00ea deixa de reagir ao dia e passa a operar com dire\u00e7\u00e3o definida.<\/p>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=&#8221;1_4&#8243; _builder_version=&#8221;4.16&#8243; custom_padding=&#8221;|||&#8221; global_colors_info=&#8221;{}&#8221; custom_padding__hover=&#8221;|||&#8221;][et_pb_code _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;]<div class=\"latepoint-book-button-wrapper wp-block-button\"><a href=\"#\" class=\"latepoint-book-button os_trigger_booking wp-block-button__link\" style=\"background-color: #ffb356; color: #ffffff\" >Quero Clareza<\/a><\/div>[\/et_pb_code][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=&#8221;4.16&#8243; max_width=&#8221;900px&#8221; custom_margin=&#8221;||40px|&#8221; custom_padding=&#8221;0|0px|0|0px|true|false&#8221; use_custom_width=&#8221;on&#8221; custom_width_px=&#8221;900px&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.16&#8243; custom_padding=&#8221;|||&#8221; global_colors_info=&#8221;{}&#8221; custom_padding__hover=&#8221;|||&#8221;][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=&#8221;3_4,1_4&#8243; admin_label=&#8221;Pricing&#8221; _builder_version=&#8221;4.16&#8243; background_color=&#8221;#ffffff&#8221; max_width=&#8221;900px&#8221; custom_margin=&#8221;|||&#8221; custom_padding=&#8221;30px|30px|30px|30px|true|true&#8221; border_radii=&#8221;on|3px|3px|3px|3px&#8221; use_custom_width=&#8221;on&#8221; custom_width_px=&#8221;900px&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;3_4&#8243; _builder_version=&#8221;4.16&#8243; custom_padding=&#8221;|||&#8221; global_colors_info=&#8221;{}&#8221; custom_padding__hover=&#8221;|||&#8221;][et_pb_text admin_label=&#8221;Package&#8221; _builder_version=&#8221;4.16&#8243; text_font=&#8221;Lato||||||||&#8221; text_font_size=&#8221;18px&#8221; text_line_height=&#8221;1.8em&#8221; header_font=&#8221;||||||||&#8221; header_3_font=&#8221;|700|||||||&#8221; header_3_line_height=&#8221;1.5em&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<h3 data-start=\"766\" data-end=\"792\">Programa Performance<\/h3>\n<p data-start=\"793\" data-end=\"887\">Para pessoas, profissionais e empreendedores que querem elevar padr\u00e3o, efici\u00eancia e autonomia.<\/p>\n<p data-start=\"889\" data-end=\"1037\">Este \u00e9 o n\u00edvel mais completo. Integramos an\u00e1lise comportamental, m\u00e9tricas avan\u00e7adas e um sistema robusto de execu\u00e7\u00e3o para consolidar autonomia real.<\/p>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=&#8221;1_4&#8243; _builder_version=&#8221;4.16&#8243; custom_padding=&#8221;|||&#8221; global_colors_info=&#8221;{}&#8221; custom_padding__hover=&#8221;|||&#8221;][et_pb_code _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;]<div class=\"latepoint-book-button-wrapper wp-block-button\"><a href=\"#\" class=\"latepoint-book-button os_trigger_booking wp-block-button__link\" style=\"background-color: #ffb356; color: #ffffff\" >Quero Performance<\/a><\/div>[\/et_pb_code][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=&#8221;4.16&#8243; max_width=&#8221;900px&#8221; custom_margin=&#8221;||40px|&#8221; custom_padding=&#8221;0|0px|0|0px|true|false&#8221; use_custom_width=&#8221;on&#8221; custom_width_px=&#8221;900px&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.16&#8243; custom_padding=&#8221;|||&#8221; global_colors_info=&#8221;{}&#8221; custom_padding__hover=&#8221;|||&#8221;][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8221;1&#8243; admin_label=&#8221;Footer&#8221; _builder_version=&#8221;4.27.4&#8243; background_color=&#8221;#FFFFFF&#8221; use_background_color_gradient=&#8221;on&#8221; background_color_gradient_stops=&#8221;#345168 5%|rgba(219,219,219,0) 100%&#8221; background_color_gradient_overlays_image=&#8221;on&#8221; background_color_gradient_start=&#8221;#345168&#8243; background_color_gradient_start_position=&#8221;5%&#8221; background_color_gradient_end=&#8221;rgba(219,219,219,0)&#8221; background_image=&#8221;https:\/\/a2byourself.com\/wp-content\/uploads\/2025\/10\/life-coach-20.jpg&#8221; min_height=&#8221;639.4px&#8221; height=&#8221;319px&#8221; custom_padding=&#8221;1.6%||0%||false|false&#8221; bottom_divider_flip=&#8221;horizontal&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_row _builder_version=&#8221;4.16&#8243; min_height=&#8221;209.7px&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.16&#8243; custom_padding=&#8221;|||&#8221; global_colors_info=&#8221;{}&#8221; custom_padding__hover=&#8221;|||&#8221;][et_pb_text admin_label=&#8221;Title&#8221; _builder_version=&#8221;4.27.4&#8243; text_font=&#8221;Lato||||||||&#8221; text_font_size=&#8221;18px&#8221; text_line_height=&#8221;1.8em&#8221; link_font=&#8221;||||||||&#8221; ul_font=&#8221;||||||||&#8221; ol_font=&#8221;||||||||&#8221; quote_font=&#8221;||||||||&#8221; header_font=&#8221;||||||||&#8221; header_2_font=&#8221;Lato|700|||||||&#8221; header_2_font_size=&#8221;40px&#8221; header_2_letter_spacing=&#8221;1px&#8221; header_2_line_height=&#8221;1.5em&#8221; header_3_font=&#8221;||||||||&#8221; header_4_font=&#8221;||||||||&#8221; header_5_font=&#8221;||||||||&#8221; header_6_font=&#8221;Lato|700|||||||&#8221; header_6_font_size=&#8221;18px&#8221; header_6_letter_spacing=&#8221;1px&#8221; header_6_line_height=&#8221;1.8em&#8221; text_orientation=&#8221;center&#8221; background_layout=&#8221;dark&#8221; max_width=&#8221;700px&#8221; module_alignment=&#8221;center&#8221; header_2_font_size_tablet=&#8221;&#8221; header_2_font_size_phone=&#8221;22px&#8221; header_2_font_size_last_edited=&#8221;on|phone&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<h2><span>Ainda tem d\u00favidas?<\/span><\/h2>\n<p>[\/et_pb_text][et_pb_contact_form captcha=&#8221;off&#8221; email=&#8221;a2byourself@gmail.com&#8221; success_message=&#8221;Thank you for contacting us. We will be in touch shortly!&#8221; submit_button_text=&#8221;Entrar em contato&#8221; module_id=&#8221;et_pb_contact_form_0&#8243; _builder_version=&#8221;4.27.4&#8243; form_field_background_color=&#8221;#ffffff&#8221; title_font=&#8221;||||||||&#8221; form_field_font=&#8221;Lato||||||||&#8221; form_field_font_size=&#8221;16px&#8221; custom_button=&#8221;on&#8221; button_text_size=&#8221;14px&#8221; button_text_color=&#8221;#ffffff&#8221; button_bg_color=&#8221;#ffb356&#8243; button_border_width=&#8221;12px&#8221; button_border_color=&#8221;#ffb356&#8243; button_border_radius=&#8221;50px&#8221; button_letter_spacing=&#8221;2px&#8221; button_font=&#8221;Lato|900||on|||||&#8221; button_icon=&#8221;&#x24;||divi||400&#8243; max_width=&#8221;700px&#8221; module_alignment=&#8221;center&#8221; animation_style=&#8221;slide&#8221; animation_direction=&#8221;bottom&#8221; animation_intensity_slide=&#8221;5%&#8221; border_radii=&#8221;on|3px|3px|3px|3px&#8221; form_background_color=&#8221;#ffffff&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_contact_field field_id=&#8221;Email&#8221; field_title=&#8221;Email Address&#8221; field_type=&#8221;email&#8221; fullwidth_field=&#8221;on&#8221; _builder_version=&#8221;4.16&#8243; global_colors_info=&#8221;{}&#8221; button_text_size__hover_enabled=&#8221;off&#8221; button_one_text_size__hover_enabled=&#8221;off&#8221; button_two_text_size__hover_enabled=&#8221;off&#8221; button_text_color__hover_enabled=&#8221;off&#8221; button_one_text_color__hover_enabled=&#8221;off&#8221; button_two_text_color__hover_enabled=&#8221;off&#8221; button_border_width__hover_enabled=&#8221;off&#8221; button_one_border_width__hover_enabled=&#8221;off&#8221; button_two_border_width__hover_enabled=&#8221;off&#8221; button_border_color__hover_enabled=&#8221;off&#8221; button_one_border_color__hover_enabled=&#8221;off&#8221; button_two_border_color__hover_enabled=&#8221;off&#8221; button_border_radius__hover_enabled=&#8221;off&#8221; button_one_border_radius__hover_enabled=&#8221;off&#8221; button_two_border_radius__hover_enabled=&#8221;off&#8221; button_letter_spacing__hover_enabled=&#8221;off&#8221; button_one_letter_spacing__hover_enabled=&#8221;off&#8221; button_two_letter_spacing__hover_enabled=&#8221;off&#8221; button_bg_color__hover_enabled=&#8221;off&#8221; button_one_bg_color__hover_enabled=&#8221;off&#8221; button_two_bg_color__hover_enabled=&#8221;off&#8221;][\/et_pb_contact_field][et_pb_contact_field field_id=&#8221;Full_Name&#8221; field_title=&#8221;Full Name&#8221; _builder_version=&#8221;4.16&#8243; global_colors_info=&#8221;{}&#8221; button_text_size__hover_enabled=&#8221;off&#8221; button_one_text_size__hover_enabled=&#8221;off&#8221; button_two_text_size__hover_enabled=&#8221;off&#8221; button_text_color__hover_enabled=&#8221;off&#8221; button_one_text_color__hover_enabled=&#8221;off&#8221; button_two_text_color__hover_enabled=&#8221;off&#8221; button_border_width__hover_enabled=&#8221;off&#8221; button_one_border_width__hover_enabled=&#8221;off&#8221; button_two_border_width__hover_enabled=&#8221;off&#8221; button_border_color__hover_enabled=&#8221;off&#8221; button_one_border_color__hover_enabled=&#8221;off&#8221; button_two_border_color__hover_enabled=&#8221;off&#8221; button_border_radius__hover_enabled=&#8221;off&#8221; button_one_border_radius__hover_enabled=&#8221;off&#8221; button_two_border_radius__hover_enabled=&#8221;off&#8221; button_letter_spacing__hover_enabled=&#8221;off&#8221; button_one_letter_spacing__hover_enabled=&#8221;off&#8221; button_two_letter_spacing__hover_enabled=&#8221;off&#8221; button_bg_color__hover_enabled=&#8221;off&#8221; button_one_bg_color__hover_enabled=&#8221;off&#8221; button_two_bg_color__hover_enabled=&#8221;off&#8221;][\/et_pb_contact_field][et_pb_contact_field field_id=&#8221;Phone_Number&#8221; field_title=&#8221;Phone Number&#8221; _builder_version=&#8221;4.16&#8243; global_colors_info=&#8221;{}&#8221; button_text_size__hover_enabled=&#8221;off&#8221; button_one_text_size__hover_enabled=&#8221;off&#8221; button_two_text_size__hover_enabled=&#8221;off&#8221; button_text_color__hover_enabled=&#8221;off&#8221; button_one_text_color__hover_enabled=&#8221;off&#8221; button_two_text_color__hover_enabled=&#8221;off&#8221; button_border_width__hover_enabled=&#8221;off&#8221; button_one_border_width__hover_enabled=&#8221;off&#8221; button_two_border_width__hover_enabled=&#8221;off&#8221; button_border_color__hover_enabled=&#8221;off&#8221; button_one_border_color__hover_enabled=&#8221;off&#8221; button_two_border_color__hover_enabled=&#8221;off&#8221; button_border_radius__hover_enabled=&#8221;off&#8221; button_one_border_radius__hover_enabled=&#8221;off&#8221; button_two_border_radius__hover_enabled=&#8221;off&#8221; button_letter_spacing__hover_enabled=&#8221;off&#8221; button_one_letter_spacing__hover_enabled=&#8221;off&#8221; button_two_letter_spacing__hover_enabled=&#8221;off&#8221; button_bg_color__hover_enabled=&#8221;off&#8221; button_one_bg_color__hover_enabled=&#8221;off&#8221; button_two_bg_color__hover_enabled=&#8221;off&#8221;][\/et_pb_contact_field][et_pb_contact_field field_id=&#8221;Message&#8221; field_title=&#8221;Message&#8221; field_type=&#8221;text&#8221; fullwidth_field=&#8221;on&#8221; _builder_version=&#8221;4.16&#8243; global_colors_info=&#8221;{}&#8221; button_text_size__hover_enabled=&#8221;off&#8221; button_one_text_size__hover_enabled=&#8221;off&#8221; button_two_text_size__hover_enabled=&#8221;off&#8221; button_text_color__hover_enabled=&#8221;off&#8221; button_one_text_color__hover_enabled=&#8221;off&#8221; button_two_text_color__hover_enabled=&#8221;off&#8221; button_border_width__hover_enabled=&#8221;off&#8221; button_one_border_width__hover_enabled=&#8221;off&#8221; button_two_border_width__hover_enabled=&#8221;off&#8221; button_border_color__hover_enabled=&#8221;off&#8221; button_one_border_color__hover_enabled=&#8221;off&#8221; button_two_border_color__hover_enabled=&#8221;off&#8221; button_border_radius__hover_enabled=&#8221;off&#8221; button_one_border_radius__hover_enabled=&#8221;off&#8221; button_two_border_radius__hover_enabled=&#8221;off&#8221; button_letter_spacing__hover_enabled=&#8221;off&#8221; button_one_letter_spacing__hover_enabled=&#8221;off&#8221; button_two_letter_spacing__hover_enabled=&#8221;off&#8221; button_bg_color__hover_enabled=&#8221;off&#8221; button_one_bg_color__hover_enabled=&#8221;off&#8221; button_two_bg_color__hover_enabled=&#8221;off&#8221;][\/et_pb_contact_field][\/et_pb_contact_form][\/et_pb_column][\/et_pb_row][\/et_pb_section]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Voc\u00ea n\u00e3o precisa se reinventar. Precisa organizar suas a\u00e7\u00f5es e disciplinar seus comportamentos.Sua mente deixa de ser um campo de distra\u00e7\u00f5es e passa a trabalhar a seu favor. Voc\u00ea reduz a dispers\u00e3o, organiza pensamentos e transforma inquieta\u00e7\u00e3o em dire\u00e7\u00e3o estrat\u00e9gica e a\u00e7\u00e3o produtiva. Saia dos ciclos de intensidade e desorganiza\u00e7\u00e3o e passe a operar com [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"nf_dc_page":"","_et_pb_use_builder":"on","_et_pb_old_content":"<!-- wp:divi\/placeholder \/-->","_et_gb_content_width":"","om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"class_list":["post-322","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.8 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Business - a2BYourself<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/a2byourself.com\/en\/business\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Business - a2BYourself\" \/>\n<meta property=\"og:description\" content=\"Voc\u00ea n\u00e3o precisa se reinventar. Precisa organizar suas a\u00e7\u00f5es e disciplinar seus comportamentos.Sua mente deixa de ser um campo de distra\u00e7\u00f5es e passa a trabalhar a seu favor. Voc\u00ea reduz a dispers\u00e3o, organiza pensamentos e transforma inquieta\u00e7\u00e3o em dire\u00e7\u00e3o estrat\u00e9gica e a\u00e7\u00e3o produtiva. Saia dos ciclos de intensidade e desorganiza\u00e7\u00e3o e passe a operar com [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/a2byourself.com\/en\/business\/\" \/>\n<meta property=\"og:site_name\" content=\"a2BYourself\" \/>\n<meta property=\"article:modified_time\" content=\"2026-06-12T17:07:52+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/a2byourself.com\\\/business\\\/\",\"url\":\"https:\\\/\\\/a2byourself.com\\\/business\\\/\",\"name\":\"Business - a2BYourself\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/a2byourself.com\\\/#website\"},\"datePublished\":\"2026-06-12T15:57:01+00:00\",\"dateModified\":\"2026-06-12T17:07:52+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/a2byourself.com\\\/business\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/a2byourself.com\\\/business\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/a2byourself.com\\\/business\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/a2byourself.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Business\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/a2byourself.com\\\/#website\",\"url\":\"https:\\\/\\\/a2byourself.com\\\/\",\"name\":\"a2BYourself\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/a2byourself.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Business - a2BYourself","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/a2byourself.com\/en\/business\/","og_locale":"en_US","og_type":"article","og_title":"Business - a2BYourself","og_description":"Voc\u00ea n\u00e3o precisa se reinventar. Precisa organizar suas a\u00e7\u00f5es e disciplinar seus comportamentos.Sua mente deixa de ser um campo de distra\u00e7\u00f5es e passa a trabalhar a seu favor. Voc\u00ea reduz a dispers\u00e3o, organiza pensamentos e transforma inquieta\u00e7\u00e3o em dire\u00e7\u00e3o estrat\u00e9gica e a\u00e7\u00e3o produtiva. Saia dos ciclos de intensidade e desorganiza\u00e7\u00e3o e passe a operar com [&hellip;]","og_url":"https:\/\/a2byourself.com\/en\/business\/","og_site_name":"a2BYourself","article_modified_time":"2026-06-12T17:07:52+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/a2byourself.com\/business\/","url":"https:\/\/a2byourself.com\/business\/","name":"Business - a2BYourself","isPartOf":{"@id":"https:\/\/a2byourself.com\/#website"},"datePublished":"2026-06-12T15:57:01+00:00","dateModified":"2026-06-12T17:07:52+00:00","breadcrumb":{"@id":"https:\/\/a2byourself.com\/business\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/a2byourself.com\/business\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/a2byourself.com\/business\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/a2byourself.com\/"},{"@type":"ListItem","position":2,"name":"Business"}]},{"@type":"WebSite","@id":"https:\/\/a2byourself.com\/#website","url":"https:\/\/a2byourself.com\/","name":"a2BYourself","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/a2byourself.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/a2byourself.com\/en\/wp-json\/wp\/v2\/pages\/322","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/a2byourself.com\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/a2byourself.com\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/a2byourself.com\/en\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/a2byourself.com\/en\/wp-json\/wp\/v2\/comments?post=322"}],"version-history":[{"count":3,"href":"https:\/\/a2byourself.com\/en\/wp-json\/wp\/v2\/pages\/322\/revisions"}],"predecessor-version":[{"id":326,"href":"https:\/\/a2byourself.com\/en\/wp-json\/wp\/v2\/pages\/322\/revisions\/326"}],"wp:attachment":[{"href":"https:\/\/a2byourself.com\/en\/wp-json\/wp\/v2\/media?parent=322"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}